{"id":4671,"date":"2021-09-13T13:39:02","date_gmt":"2021-09-13T13:39:02","guid":{"rendered":"https:\/\/staging.docfinder.farm\/ratgeber\/?post_type=article&#038;p=4671"},"modified":"2023-02-27T13:47:34","modified_gmt":"2023-02-27T12:47:34","slug":"wie-funktioniert-eine-strahlentherapie","status":"publish","type":"article","link":"https:\/\/www.docfinder.at\/wissensmagazin\/wie-funktioniert-eine-strahlentherapie\/","title":{"rendered":"Wie funktioniert eine Strahlentherapie?"},"content":{"rendered":"<h2><strong>Wie funktioniert die Strahlentherapie?<\/strong><\/h2>\n<p>Die Strahlentherapie ist im Gegensatz zu systemischen Therapien wie etwa der&nbsp;<a title=\"Was passiert bei einer Chemotherapie?\" href=\"https:\/\/www.docfinder.at\/ratgeber\/was-passiert-bei-einer-chemotherapie-6821\">Chemotherapie<\/a>, die ihre Wirkung im ganzen K\u00f6rper entfaltet, eine lokale Form der Therapie, die in der Krebsbehandlung eingesetzt wird und die ausschlie\u00dflich in der behandelten Region wirkt. Sie kann als alleinige Therapie oder in Kombination mit anderen Therapien wie etwa der Chemotherapie erfolgen und vor oder nach einer&nbsp; Operation oder einer medikamento\u0308sen Behandlung stattfinden. Ziel der Behandlung ist es, Tumorzellen zu zerst\u00f6ren ohne dabei zu viele gesunde Zellen zu sch\u00e4digen. Die Wirkung beruht darauf, dass die Strahlung die Erbsubstanz der Zellen so ver\u00e4ndert, dass die Zellen ihre Teilungsfa\u0308higkeit verlieren und absterben.&nbsp; Gelingt das, so werden die Tumorzellen anschlie\u00dfend von k\u00f6rpereigenen Immunzellen zerlegt und abtransportiert.<\/p>\n<p>Eine Strahlentherapie kann zu verschiedenen Zeitpunkten der Krebsbehandlung und bei 80 Prozent der Patienten ambulant durchgef\u00fchrt werden: Geschieht das vor der Operation, so kann sie das Ausma\u00df der Operation reduzieren, wodurch oft das betroffene Organ erhalten werden kann. Wird die Strahlentherapie nach der Operation angewendet, so k\u00f6nnen verbliebene Tumorzellen zerst\u00f6rt werden. Das verhindert in einem hohen Ausma\u00df das Wiederauftreten der Erkrankung.<\/p>\n<p>Ist das Ziel der Bestrahlung die Heilung, spricht man von kurativer Strahlentherapie. Wenn eine Heilung nicht m\u00f6glich und das Ziel der Therapie eine Linderung von Beschwerden ist, spricht man von einer palliativen Strahlentherapie.<\/p>\n<h2><strong>Wie l\u00e4uft eine Strahlentherapie ab?<\/strong><\/h2>\n<p>Eine Strahlentherapie muss immer sorgfa\u0308ltig geplant und vorbereitet werden. Der Tumor soll&nbsp; mit m\u00f6glichst hohen Dosen bestrahlt, das gesunde Gewebe hingegen nur mit geringen Dosen belastet werden. Dabei wird auch ein Planungs-CT des Patienten in jener Lagerung, in der auch die sp\u00e4tere Bestrahlung stattfindet, durchgefu\u0308hrt und die Haut pr\u00e4zise dort, wo sie bestrahlt werden soll, mit einem Stift markiert.<\/p>\n<p>Je nachdem, um welche Art von Tumor es sich handelt und wie er sich ausgebreitet hat, wird die Anzahl der Bestrahlungen vom Arzt festgelegt. Bei sehr kleinen Tumoren kann bereits eine einmalige oder nur wenige hoch dosierte Bestrahlungen gen\u00fcgen, aber mehrheitlich finden die rund zehn bis 15 Minuten dauernden Sitzungen f\u00fcnfmal pro Woche \u00fcber einen Zeitraum von zwei bis acht Wochen statt.<\/p>\n<h2><strong>Was passiert bei einer Strahlentherapie im K\u00f6rper?<\/strong><\/h2>\n<p>Im Gewebe erzeugt die Strahlung Ionen. Diese reagieren mit umliegenden Molek\u00fclen, welche sich dadurch ver\u00e4ndern und wiederum Reaktionen mit weiteren Molek\u00fclen eingehen k\u00f6nnen. Durch diese Ver\u00e4nderungen k\u00f6nnen Zellen funktionsunf\u00e4hig werden oder absterben. Gesunde Zellen k\u00f6nnen sich bis zu einem gewissen Grad regenerieren und eingetretene Sch\u00e4den k\u00f6nnen mit der Zeit auch repariert werden.<\/p>\n<h2><strong>Formen der Strahlentherapie<\/strong><\/h2>\n<p>Es gibt verschiedene Bestrahlungsmethoden. Nicht alle sind f\u00fcr alle Krebsarten gleich gut geeignet. Genaue Information \u00fcber die geeignetste Strahlentherapie im individuellen Fall erh\u00e4lt man vom behandelnden Arzt.<\/p>\n<p><strong>Bestrahlung von au\u00dfen (Teletherapie):<\/strong>&nbsp;Dabei werden Haut, Fett- und Bindegewebe, eventuell auch Organe durchdrungen, um das Tumorgewebe zu treffen.<\/p>\n<p><strong>Kontaktbestrahlung (Brachytherapie):<\/strong>&nbsp;bei kleinen, gut zug\u00e4nglichen Tumoren werden die radioaktiven Quellen mit einem Applikator nahe an das zu bestrahlende Gewebe herangebracht oder direkt in das Organ oder Tumorgewebe eingef\u00fchrt. Die Brachytherapie ist zum Beispiel bei&nbsp;<a title=\"Geb\u00e4rmutterhalskrebs (Zervixkarzinom) \u2013 Was ist das?\" href=\"https:\/\/www.docfinder.at\/ratgeber\/gebaermutterhalskrebs-4078\">Geb\u00e4rmutterhalskrebs<\/a>, Prostatakrebs, Sarkomen oder Kopf-Hals-Tumoren geeignet.<\/p>\n<p><strong>Intraoperative Strahlentherapie (IORT):<\/strong>&nbsp;Wenn bei einer Operation mikroskopische Tumorreste im so genannten Tumorbett zur\u00fcckbleiben, wird dieses Tumorbett w\u00e4hrend der OP mit der h\u00f6chstm\u00f6glichen Strahlendosis bestrahlt. Die IORT eignet sich f\u00fcr Bestrahlungen im Bauchraum und f\u00fcr die brusterhaltende Behandlung des&nbsp;<a title=\"Brustkrebs \u2013 Definition, Diagnose und Behandlung\" href=\"https:\/\/www.docfinder.at\/ratgeber\/brustkrebs-2552\">Mammakarzinoms.<\/a><\/p>\n<p><strong>Stereotaktische Strahlentherapie:<\/strong>&nbsp;Dabei handelt es sich um eine sehr pr\u00e4zise Technologie, die eine Art Operation ohne Messer erlaubt. Die Behandlungsstrahlen treffen aus verschiedenen Einstrahlwinkeln punktgenau auf den Tumor, sodass dieser mit hohen Energiedosen bestrahlt werden kann. Diese Art der Bestrahlung eignet sich f\u00fcr Hirntumoren, Tumoren im Kopf-Halsbereich sowie Tumoren in&nbsp;<a title=\"Lungenkrebs \u2013 Stadien, Symptome, Diagnose, Behandlung\" href=\"https:\/\/www.docfinder.at\/ratgeber\/lungenkrebs-stadien-symptome-diagnose-behandlung-5210\">Lunge<\/a>, Leber, Prostata und Wirbels\u00e4ule.<\/p>\n<p><strong>Bildgefu\u0308hrte Strahlentherapie (IGRT:<\/strong>&nbsp;Image Guided Radio Therapy): Diese Art der Bestrahlung kommt zum Einsatz, wenn ein Tumor beweglich ist, was h\u00e4ufig der Fall ist. Mit der IGRT wird vor der Strahlenbehandlung die aktuelle Lage des Tumors sichtbar gemacht, sodass diese vor jeder Sitzung verfolgt werden kann.<\/p>\n<p><strong>Intensita\u0308tsmodulierte Strahlentherapie:<\/strong>&nbsp;(IMRT: Intensity Modulated Radio Therapy): Dabei kann die Dosisverteilung innerhalb eines Strahlenfeldes variiert werden. Die IMRT ist bei Prostatakrebs, Hirntumoren, Tumoren im Kopf-Hals-Bereich, Tumoren des Verdauungstrakts und im Genitalbereich einsetzbar.<\/p>\n<p><strong>Protonentherapie:<\/strong>&nbsp;Diese Form der Bestrahlung hat den Vorteil, dass eine geringere Strahlenbelastung der den Tumor umgebenden Normalgeweben stattfindet. Sie wird bei Kindern, bei Tumoren im Bereich der Sch\u00e4delbasis oder solchen mit enger Nachbarschaft zu kritischen Strukturen und bei Rezidiven in kritischen Regionen eingesetzt.<\/p>\n<p><strong>Nuklearmedizinische Anwendungen:<\/strong>&nbsp;Dabei werden radioaktive Substanzen verwendet, die in Form von Arzneimitteln in den K\u00f6rper eingebracht werden, zum Beispiel durch Injektionen. Die Substanzen gelangen durch den Stoffwechsel in das betroffene Organ, zerst\u00f6ren die krankhaften Zellen und zerfallen dann. Angewandt wird diese Art der Strahlentherapie etwa bei Knochenmetastasen.<\/p>\n<h2><strong>M\u00f6gliche Nebenwirkungen einer Strahlentherapie<\/strong><\/h2>\n<p>Gesundes Gewebe in der Umgebung des Tumors wird bei heutigen Strahlentherapien immer besser geschont. Trotzdem gibt es eine Reihe von Nebenwirkungen, die auftreten k\u00f6nnen:<\/p>\n<ul>\n<li>Ersch\u00f6pfung: Da der Krebs selbst Ressourcen des K\u00f6rpers verbraucht und auch die Strahlentherapie f\u00fcr den Organismus anstrengend ist, kann es zur so genannten&nbsp;<a title=\"Chronisches Ersch\u00f6pfungssyndrom\" href=\"https:\/\/www.docfinder.at\/ratgeber\/chronisches-erschoepfungssyndrom-chronisches-fatigue-syndrom-6189\">Fatigue<\/a>&nbsp;kommen.<\/li>\n<li>\u00dcbelkeit und Durchfall: Dazu kann es fallweise etwa bei Bestrahlungen im Bauchraum kommen. Diese Nebenwirkungen k\u00f6nnen aber mit Medikamenten sehr gut behandelt werden.<\/li>\n<li>Hautprobleme: M\u00f6glich sind leichte R\u00f6tungen und sonnenbrand\u00e4hnliche Beschwerden. Bei einer Strahlendosis, die sehr hoch ist, kann es auch zu st\u00e4rkeren Reaktionen kommen, zum Beispiel zu Blasen und kleinere und gr\u00f6\u00dfere Wunden. Die Schleimhaut im Intimbereich kann wund werden, schmerzen oder bluten. Mit Hautsch\u00e4den ist aber nur in den Bereichen zu rechnen, die im Strahlenfeld liegen. Fast alle dieser Probleme geben sich mit dem Ende der Bestrahlung.<\/li>\n<li>Haarausfall: Bei einer Bestrahlung des Kopfes k\u00f6nnen die Kopfhaare, Wimpern oder Augenbrauen ausfallen, bei einer Bestrahlung des Oberk\u00f6rper verliert man vielleicht die Achselbehaarung. Die H\u00f6he der Strahlendosis spielt dabei eine Rolle. In der Regel wachsen die Haare nach Ende der Strahlentherapie wieder nach.<\/li>\n<li>Schleimhautentzu\u0308ndungen: M\u00f6glich sind R\u00f6tungen, Schwellungen und Reizungen, sp\u00e4ter auch kleine, schmerzhafte Verletzungen, die schlecht abheilen und sich leicht infizieren. Bestehende Zahn- und Zahnfleischprobleme k\u00f6nnen sich verschlechtern. Eine gute Pflege ist ist hier w\u00e4hrend und auch nach der Strahlentherapie wichtig.<\/li>\n<li>Organsch\u00e4den: Organe, die der Strahlung ausgesetzt sind, k\u00f6nnen mit einer Entz\u00fcndung reagieren, langfristig vernarben oder verkleben. Das Risiko h\u00e4ngt sehr von der Strahlendosis ab.<\/li>\n<\/ul>\n<h2><strong>Ern\u00e4hrung w\u00e4hrend einer Strahlentherapie<\/strong><\/h2>\n<p>Wenn der Verdauungstrakt nicht im Bestrahlungsfeld liegt, muss der betroffene Patient in der Regel die Essgewohnheiten nicht umstellen. Eine besondere Ern\u00e4hrungstherapie ist also nicht notwendig, es wird jedoch geraten, auf eine sorgfa\u0308ltig zusammengestellte Auswahl der Lebensmittel und Getr\u00e4nke zu achten, um weitere Reizungen zu vermeiden. Drohen Gewichtsverlust oder Mangelern\u00e4hrung, so wird der fr\u00fchzeitige Einsatz von Trinknahrung und eine Beratung durch Ern\u00e4hrungsspezialisten empfohlen.<br \/>\nDas kann zum Beispiel bei Patienten, die im Kopf- und Halsbereich bestrahlt werden, der Fall sein. Bei ihnen bzw. auch bei allen, die aufgrund ihrer Tumorerkrankung Schwierigkeiten mit dem Schlucken haben, kann auch f\u00fcr eine Zeitlang eine Magensonde notwendig werden.<br \/>\nWas Nahrungserg\u00e4nzungsmittel, zus\u00e4tzliche Vitamine oder Mineralstoffe betrifft, so sollte jeder Patient eine etwaige Einnahme mit dem behandelnden Arzt besprechen, denn noch ist umstritten, ob diese Substanzen nicht mehr schaden als n\u00fctzen, weil sie unter anderem auch die Strahlenwirkung abschw\u00e4chen k\u00f6nnen.<\/p>\n","protected":false},"author":41,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[26,25,2459,78,2416,2405,2424,2448,7,2429,2408,2411,1895,2455],"tags":[216,793,75,687],"class_list":["post-4671","article","type-article","status-publish","has-post-thumbnail","hentry","category-allgemeinmedizin","category-chirurgie","category-frauenheilkunde","category-gastroenterologie","category-hals-nasen-ohrenheilkunde","category-haut-und-geschlechtskrankheiten","category-hepatologie","category-innere-medizin","category-leben","category-nephrologie","category-neurologie","category-onkologie","category-radiologie","category-urologie","tag-krebs","tag-krebsbehandlung","tag-onkologie","tag-strahlentherapie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article\/4671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/users\/41"}],"version-history":[{"count":5,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article\/4671\/revisions"}],"predecessor-version":[{"id":9862,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article\/4671\/revisions\/9862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/media\/4672"}],"wp:attachment":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/media?parent=4671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/categories?post=4671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/tags?post=4671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}