{"id":1646,"date":"2018-09-10T12:12:43","date_gmt":"2018-09-10T12:12:43","guid":{"rendered":"http:\/\/localhost\/ratgeber\/article\/chlamydien\/"},"modified":"2023-02-27T12:45:20","modified_gmt":"2023-02-27T11:45:20","slug":"chlamydien","status":"publish","type":"article","link":"https:\/\/www.docfinder.at\/wissensmagazin\/chlamydien\/","title":{"rendered":"Chlamydien &#8211; Definition, Formen, Symptome, Behandlung"},"content":{"rendered":"<h2>Was sind Chlamydien?<\/h2>\n<p>Bei Chlamydien handelt es sich um eine Familie von Bakterien. H\u00e4ufig wird mit Chlamydien bzw. einer Chlamydien-Infektion in erster Linie eine Geschlechtskrankheit assoziiert (urogenitale Chlamydien-Infektion), allerdings k\u00f6nnen Chlamydien je nach Spezies und Serotyp (Untergruppe von Mikroorganismen) beim Menschen verschiedene Krankheitsbilder hervorrufen, nicht nur eine Infektion der Harn- und Geschlechtsorgane.<\/p>\n<h2>Erkrankungen durch Chlamydien<\/h2>\n<p>Insgesamt gibt es drei Spezies der Gattung Chlamydia, die beim Menschen Erkrankungen hervorrufen k\u00f6nnen, dazu z\u00e4hlen:<\/p>\n<h3>Chlamydia trachomatis<\/h3>\n<p>Serotypen A-C als Erreger des Trachoms (chronisch-follikul\u00e4re <a href=\"\/ratgeber\/bindehautentzuendung-3263\">Bindehautentz\u00fcndung<\/a>), \u00dcbertragung zumeist durch eine Schmierinfektion; Serotypen D-K als Erreger von urogenitalen Infektionen, \u00dcbertragung bei sexuellen Kontakten; Serotypen L1-L3 als Erreger des Lymphogranuloma inguinale (Geschlechtskrankheit), \u00dcbertragung durch Geschlechtsverkehr<\/p>\n<h3>Chlamydia psittaci<\/h3>\n<p>Erreger der Ornithose (Infektionskrankheit, die sich als grippaler Infekt oder atypische <a href=\"\/ratgeber\/behandlung-einer-lungenentzuendung-1060\">Lungenentz\u00fcndung<\/a> \u00e4u\u00dfern kann), \u00dcbertragung durch direkten Kontakt mit infizierten V\u00f6geln oder eine Tr\u00f6pfcheninfektion durch das Einatmen von vogelmistlastigem Staub<\/p>\n<h3>Chlamydia pneumoniae<\/h3>\n<p>Erreger der Pneumonie, \u00dcbertragung durch Tr\u00f6pfcheninfektion<\/p>\n<p><strong>Erl\u00e4uterungen:<\/strong> &#8220;Atypisch&#8221; bedeutet so viel wie &#8220;eine Abweichung vom Normalen&#8221;. Bei einer Schmierinfektion erfolgt die \u00dcbertragung von Krankheitserregern durch die Ber\u00fchrung eines Lebewesens oder Objekts &#8211; beispielsweise werden die Erreger bei der gemeinsamen Nutzung von Besteck oder eines Handtuchs, welches mit infekti\u00f6sen K\u00f6rpersekreten kontaminiert ist abgestreift und gelangen so auf die Haut oder Schleimhaut. Bei einer Tr\u00f6pfcheninfektion werden die Erreger beim Husten, Sprechen oder Niesen durch kleinste Tr\u00f6pfchen \u00fcbertragen.<\/p>\n<h2>Symptome<\/h2>\n<p>Bindehautentz\u00fcndung, urogenitale Infektion, Lungenentz\u00fcndung &#8211; Chlamydien k\u00f6nnen verschiedene Krankheitsbilder und folglich eine Vielzahl an Symptomen verursachen.<\/p>\n<h3>Merkmale eines Trachoms<\/h3>\n<p>Je nach Stadium, u. a. unspezifische Bindehautreizung, Fremdk\u00f6rpergef\u00fchl, Tr\u00e4nentr\u00e4ufeln, Follikelansammlung und Vernarbungen im Bereich der Bindehaut, Wimpernscheuern, Hornhautreizung (Trichiasis), Hornhautabsch\u00fcrfung, unvollst\u00e4ndiger Lidschluss und reduzierter Tr\u00e4nenfluss, am Ende kann die vollst\u00e4ndige Erblindung stehen. Das Trachom ist eine der h\u00e4ufigsten Augenerkrankungen weltweit, findet sich in den Industriestaaten allerdings nur sehr selten.<\/p>\n<h3>Genitale Chlamydien-Infektion<\/h3>\n<p>Die Zahl der sexuell \u00fcbertragbaren Erkrankungen nimmt in Europa zu und Chlamydien sind die mitunter h\u00e4ufigsten bakteriellen Erreger sexuell \u00fcbertragbarer Infektionen. Hochrisikogruppe sind sexuell aktive junge Menschen, Frauen sind \u00f6fter betroffen als M\u00e4nner. In vielen F\u00e4llen verl\u00e4uft die Chlamydien-Infektion ohne erkennbare Symptome. H\u00e4ufig bleibt sie unbemerkt und unbehandelt, was unter Umst\u00e4nden schwere Folgen haben kann.<\/p>\n<p>Wenn es doch zu Beschwerden kommt, dann machen sich diese u. a. durch Schmerzen, Juckreiz und Ausfluss bemerkbar. Bei Frauen kann eine Chlamydien-Infektion zu einer Entz\u00fcndung des Geb\u00e4rmutterhalses und der Harnr\u00f6hre f\u00fchren (Zervizitis, Urethritis), m\u00f6gliche Symptome sind schleimig-eitriger und intensiv riechender Ausfluss, h\u00e4ufiger Harndrang und Schmerzen beim Harnlassen. Unbehandelt k\u00f6nnen die Bakterien aufsteigen, die Entz\u00fcndung geht dann auf die Geb\u00e4rmutterschleimhaut, die Eileiter und Eierst\u00f6cke \u00fcber, m\u00f6gliche Folgen sind chronische Unterleibsschmerzen bis hin zu Unfruchtbarkeit, ferner gehen urogenitale Infektionen mit einem erh\u00f6hten Risiko f\u00fcr extrauterine Schwangerschaften einher. Ist auch die Bauchh\u00f6hle von der Infektion betroffen kann es u. a. zu Bauchfellentz\u00fcndungen und Perihepatitis (Einbezug der Leberkapsel) mit Symptomen wie Abgeschlagenheit, Fieber und rechtseitigen Oberbauchschmerzen kommen.<\/p>\n<h3>Symptome einer Urogenitalen Infektion beim Mann<\/h3>\n<p>Druckgef\u00fchl, Schmerzen und Brennen beim Harnlassen und eitriger Ausfluss, unbehandelt k\u00f6nnen sich die Erreger bis in die Prostata, Hoden und Nebenhoden ausbreiten und Entz\u00fcndungen verursachen (Prostataentz\u00fcndung, Hoden- und Nebenhodenentz\u00fcndung). Abh\u00e4ngig von den sexuellen Gewohnheiten k\u00f6nnen die Erreger auch in den Rachen oder Enddarm gelangen (Oral-, Analverkehr). M\u00f6gliche Symptome einer Enddarmentz\u00fcndung sind Juckreiz und Stuhlbeimengungen, eine Rachenentz\u00fcndung kann u. a. mit Hals- und Schluckschmerzen einhergehen. Die Infektion kann sich w\u00e4hrend der Geburt auf das Kind \u00fcbertragen und beim Neugeborenen zu einer Bindehaut-, Mittelohr- oder Lungenentz\u00fcndung f\u00fchren.<\/p>\n<h3>Durch Chlamydien verursachtes Lymphogranuloma venereum<\/h3>\n<p>Mit Symptomen und Anzeichen wie kleinen Bl\u00e4schen und Hautgeschw\u00fcren (zumeist im Intimbereich), geschwollenen Lymphknoten in der Leistengegend, Abszessen, Eiteraustritt u. a. Auch ein Befall des Rektums und Rachens ist m\u00f6glich. Chlamydia pneumoniae bef\u00e4llt die Atemwege und kann zu einer Nasennebenh\u00f6hlen- und Rachenentz\u00fcndung (Sinusitis, Pharyngitis), Bronchitis und atypischen Lungenentz\u00fcndung f\u00fchren, m\u00f6gliche Beschwerden sind Kopfschmerzen, Fieber, Husten, Halsschmerzen, Schluckbeschwerden u. a. Risikofaktoren f\u00fcr sexuell \u00fcbertragbare Chlamydien sind zusammengefasst u. a. Oralsex, Vaginal- und Analverkehr, v. a. ohne Kondom, und kontaminierte Sexspielzeuge.<\/p>\n<p>Die Auflistung der hier angef\u00fchrten Anzeichen und Symptome kann unvollst\u00e4ndig sein, zudem kann ein Symptom bei Auftreten harmlos oder Anzeichen f\u00fcr eine andere Erkrankung sein. Auch muss nicht jedes hier angef\u00fchrte Symptom beim jeweiligen durch Chlamydien verursachten Krankheitsbild auftreten. Im Zweifelsfall oder bei Verdacht auf eine Erkrankung sollte stets das \u00e4rztliche Gespr\u00e4ch gesucht werden.<\/p>\n<h2>Diagnose<\/h2>\n<p>Ansprechpartner bei entsprechenden Beschwerden sind \u00c4rzte f\u00fcr Allgemeinmedizin, Gyn\u00e4kologen, Urologen, Dermatologen und Augen\u00e4rzte. Zu Beginn steht die genaue Anamnese. Die k\u00f6rperliche Untersuchung richtet sich nach der Verdachtsdiagnose (z. B. Untersuchung der Geschlechtsorgane und des Afters, Tastuntersuchung des Bauches und Untersuchung der Lymphknoten bei Verdacht auf urogenitale Infektion, Abklopfen und Abh\u00f6ren der Lunge bei m\u00f6glicher Infektion der Atemwege, Inspektion des Rachens, Untersuchung der Augen), ebenso wie m\u00f6gliche weitere Untersuchungen (z. B. Ultraschalluntersuchung bei Verdacht auf urogenitale Infektion bei Frauen). Au\u00dferdem gibt es verschiedene Chlamydien-Tests, mittels welcher die Erreger in einer Probe des Patienten (Abstrich aus der Harnr\u00f6hre, von der Geb\u00e4rmutterschleimhaut, aus dem Analbereich und Rachen, Augensekret, Urin, Auswurf u. a.) oder Antik\u00f6rper im Blut nachgewiesen werden k\u00f6nnen (Blutuntersuchung). Ein Chlamydien-Test zur Abkl\u00e4rung einer m\u00f6glichen sexuell \u00fcbertragenen Erkrankung ist u. a. sinnvoll bei jungen sexuell aktiven Erwachsenen, bei Frauen und M\u00e4nnern mit mehreren oder neuen Sexualpartnern und Beschwerden unklarer Ursache (z. B. Unterbauchschmerzen, Ausfluss).<\/p>\n<h2>Behandlung<\/h2>\n<p>Chlamydien-Infektionen werden mit Antibiotika behandelt, bei urogenitalen Chlamydien-Infektionen muss\/m\u00fcssen der\/die Sexualpartner ebenfalls behandelt werden. Weiters gibt es je nach Krankheitsbild weitere Ma\u00dfnahmen, um die Behandlung zu unterst\u00fctzen. Bei rechtzeitiger Abkl\u00e4rung und ad\u00e4quater Behandlung heilt eine Chlamydien-Infektion in der Regel folgenlos aus.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":48,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[2459,66,2457,6,2455],"tags":[370,1346,947,129,18,784,190],"class_list":["post-1646","article","type-article","status-publish","has-post-thumbnail","hentry","category-frauenheilkunde","category-gesundheitsnews","category-krankheit","category-sexualitaet","category-urologie","tag-bakterien","tag-chlamydien","tag-frauen","tag-frauenheilkunde","tag-kinderwunsch","tag-sexualitat","tag-urologie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article\/1646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/users\/48"}],"version-history":[{"count":5,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article\/1646\/revisions"}],"predecessor-version":[{"id":10252,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/article\/1646\/revisions\/10252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/media\/1647"}],"wp:attachment":[{"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/media?parent=1646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/categories?post=1646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.docfinder.at\/wissensmagazin\/wp-json\/wp\/v2\/tags?post=1646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}